{"id":6428,"date":"2026-03-16T09:56:30","date_gmt":"2026-03-16T08:56:30","guid":{"rendered":"https:\/\/esmfoundation.org\/?p=6428"},"modified":"2026-05-07T10:56:27","modified_gmt":"2026-05-07T08:56:27","slug":"tagung-nachhaltige-versorgung-mit-kritischen-rohstoffen-und-komponenten-fuer-die-zukunft-des-technologiestandorts-schweiz","status":"publish","type":"post","link":"https:\/\/esmfoundation.org\/de\/2026\/03\/16\/tagung-nachhaltige-versorgung-mit-kritischen-rohstoffen-und-komponenten-fuer-die-zukunft-des-technologiestandorts-schweiz\/","title":{"rendered":"Tagung am 13. Mai: \u00abNachhaltige Versorgung mit kritischen Rohstoffen und Komponenten f\u00fcr die Zukunft des Technologiestandorts Schweiz\u00bb"},"content":{"rendered":"\n<p><strong>Datum: <\/strong>13. Mai 2026<\/p>\n\n\n\n<p><strong>Ort:<\/strong> Switzerland Innovation Park Biel\/Bienne, Aarbergerstrasse 46, 2503 Biel\/Bienne&nbsp;<\/p>\n\n\n\n<p><strong>Organisiert von: <\/strong>Stiftung ESM, Schweizerischen Akademie der Wissenschaften SATW, Switzerland Innovation Park Biel Bienne (SIPBB), Eigen\u00f6ssischen Materialpr\u00fcfungs- und Forschungsanstalt (Empa)<\/p>\n\n\n\n<p><strong>Unterst\u00fctzt durch:<\/strong> Standortf\u00f6rderung des Kantons Bern<\/p>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"797\" height=\"254\" src=\"https:\/\/esmfoundation.org\/wp-content\/uploads\/2026\/03\/Standortfoerderung-Kanton-Bern-Logo.jpg\" alt=\"\" class=\"wp-image-7023\" style=\"width:200px\" srcset=\"https:\/\/esmfoundation.org\/wp-content\/uploads\/2026\/03\/Standortfoerderung-Kanton-Bern-Logo.jpg 797w, https:\/\/esmfoundation.org\/wp-content\/uploads\/2026\/03\/Standortfoerderung-Kanton-Bern-Logo-300x96.jpg 300w, https:\/\/esmfoundation.org\/wp-content\/uploads\/2026\/03\/Standortfoerderung-Kanton-Bern-Logo-768x245.jpg 768w\" sizes=\"(max-width: 797px) 100vw, 797px\" \/><\/figure>\n\n\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>Die sichere und nachhaltige Versorgung mit kritischen Rohstoffen und Komponenten ist zentral f\u00fcr den Technologiestandort Schweiz. Geopolitische Spannungen, Lieferkettenrisiken und steigende Nachfrage stellen Industrie, Politik und Forschung vor grosse Herausforderungen, bieten aber auch Chancen f\u00fcr Innovation und Kreislaufwirtschaft.<\/p>\n\n\n\n<p>Um diese Chancen und Risiken zu diskutieren, hat sich die Stiftung ESM mit der Schweizerischen Akademie der Wissenschaften SATW, dem Switzerland Innovation Park Biel Bienne (SIPBB) und der Eigen\u00f6ssischen Materialpr\u00fcfungs- und Forschungsanstalt (Empa) zusammengeschlossen, um an einer Tagung am 13. Mai 2026 verschiedene Sichtweisen aus der Industrie, Verb\u00e4nden und Forschung zusammenzubringen. Ziel ist es, sektor\u00fcbergreifend Wissen zu b\u00fcndeln, Risiken sichtbar zu machen und konkrete Handlungsempfehlungen f\u00fcr Wirtschaft und Politik zu formulieren.<\/p>\n\n\n\n<p>Am Vormittag (auf Einladung) stehen in interaktiven Arbeitsgruppen von Expert:innen sektorspezifische Fragestellungen im Zentrum. Am Nachmittag (\u00f6ffentlich) werden die Ergebnisse aus den Workshops reflektiert und in einen \u00fcbergeordneten Kontext gestellt.<\/p>\n\n\n\n<p><strong>\u00d6ffentlicher Programmteil&nbsp;<\/strong><\/p>\n\n\n\n<p><strong>Ab<\/strong> <strong>13:30:<\/strong> Eintreffen, Kaffee<br><strong>14.00<\/strong>: Begr\u00fcssung durch das Organisationskomitee<br><strong>14.20: <\/strong>Begr\u00fcssung durch Nationalr\u00e4tin Elisabeth Schneider-Schneiter <br><strong>14.30: <\/strong>Begr\u00fcssung durch Oliver Nievergelt, Staatssekretariat f\u00fcr Wirtschaft<br><strong>14.35:<\/strong> Erste Erkenntnisse aus den Workshops<br><strong>14.45:<\/strong> Diversifizierungsstrategien bei Ypsomed \u2013 Nationalrat Simon Michel, CEO Ypsomed<br><strong>15.00:<\/strong> Souver\u00e4ne Systeme: Wege zur digitalen Resilienz \u2013 Nationalrat Gerhard Andrey<br><strong>15.15:<\/strong> Kritikalit\u00e4tsbewertung und Rohstoffstrategien der EU \u2013 Luis Tercero, Fraunhofer ISI, D<br><strong>15.30:<\/strong> Nachhaltige Rohstoffversorgung f\u00fcr die Schweiz: Verantwortung in globalen Lieferketten st\u00e4rken -Robert Bachmann (Public Eye)<br><strong>15.45:<\/strong> Industrie-Input &#8211; Jan Backmann (Roche), Sabine Krattiger (Immark), Michael Baumgartner (Maxon)<br><strong>16.00:<\/strong> Paneldiskussion: Wie kann Resilienz und Kreislaufwirtschaft f\u00fcr kritische Rohstoffe in der Schweiz gest\u00e4rkt werden? &nbsp;&#8211; Mit Nationalr\u00e4tin Elisabeth Schneider-Schneiter, Nationalrat Gerhard Andrey, Jan Backmann (Roche), Sabine Krattiger (Immark), Michael Baumgartner (Maxon)<br><strong>17.00:<\/strong> Schlussworte durch Virve Resta, Fachspezialistin Kreislaufwirtschaft und Innovation, Standortf\u00f6rderung Kanton Bern<\/p>\n\n\n\n<p><strong>Bis 19 Uhr:<\/strong> Ap\u00e9ro Riche<br><strong>17.30:<\/strong> Optionaler Rundgang durch den SIPBB<\/p>\n\n\n\n<p>Die Resultate der Tagung (Status quo, Handlungsempfehlungen, W\u00fcnsche an die Politik) werden im Anschluss in Form eines Leitfadens f\u00fcr Politik und \u00d6ffentlichkeit publiziert.<\/p>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/eventfrog.ch\/de\/p\/kurse-seminare\/sonstige-kurse-seminare\/nachhaltige-versorgung-mit-kritischen-rohstoffen-7432347496012113353.html\" target=\"_blank\" rel=\"noreferrer noopener\">Melden Sie sich an<\/a><\/div>\n\n\n\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/esmfoundation.org\/wp-content\/uploads\/2026\/03\/Medienmitteilung.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">Medienmitteilung herunterladen<\/a><\/div>\n<\/div>\n\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p><strong>Interessieren Sie sich f\u00fcr die Teilnahme an den Expert:innen-Workshops am Vormittag?<\/strong> <br>Kontaktieren Sie bitte das Organisationsteam: alessandra.hool@esmfoundation.org.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Datum: 13. Mai 2026 Ort: Switzerland Innovation Park Biel\/Bienne, Aarbergerstrasse 46, 2503 Biel\/Bienne&nbsp; Organisiert von: Stiftung ESM, Schweizerischen Akademie der Wissenschaften SATW, Switzerland Innovation Park Biel Bienne (SIPBB), Eigen\u00f6ssischen Materialpr\u00fcfungs- und Forschungsanstalt (Empa) Unterst\u00fctzt durch: Standortf\u00f6rderung des Kantons Bern Die sichere und nachhaltige Versorgung mit kritischen Rohstoffen und Komponenten ist zentral f\u00fcr den Technologiestandort Schweiz&#8230;. <\/p>\n<div class=\"clear\"><\/div>\n<p><a href=\"https:\/\/esmfoundation.org\/de\/2026\/03\/16\/tagung-nachhaltige-versorgung-mit-kritischen-rohstoffen-und-komponenten-fuer-die-zukunft-des-technologiestandorts-schweiz\/\" class=\"excerpt-read-more\">Read More<\/a><\/p>\n","protected":false},"author":395,"featured_media":6511,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_ti_tpc_template_sync":false,"_ti_tpc_template_id":"","footnotes":""},"categories":[72,69],"tags":[],"class_list":["post-6428","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-bevorstehende-veranstaltungen","category-veranstaltungen"],"_links":{"self":[{"href":"https:\/\/esmfoundation.org\/de\/wp-json\/wp\/v2\/posts\/6428"}],"collection":[{"href":"https:\/\/esmfoundation.org\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/esmfoundation.org\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/esmfoundation.org\/de\/wp-json\/wp\/v2\/users\/395"}],"replies":[{"embeddable":true,"href":"https:\/\/esmfoundation.org\/de\/wp-json\/wp\/v2\/comments?post=6428"}],"version-history":[{"count":9,"href":"https:\/\/esmfoundation.org\/de\/wp-json\/wp\/v2\/posts\/6428\/revisions"}],"predecessor-version":[{"id":7027,"href":"https:\/\/esmfoundation.org\/de\/wp-json\/wp\/v2\/posts\/6428\/revisions\/7027"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/esmfoundation.org\/de\/wp-json\/wp\/v2\/media\/6511"}],"wp:attachment":[{"href":"https:\/\/esmfoundation.org\/de\/wp-json\/wp\/v2\/media?parent=6428"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/esmfoundation.org\/de\/wp-json\/wp\/v2\/categories?post=6428"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/esmfoundation.org\/de\/wp-json\/wp\/v2\/tags?post=6428"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}